{"id":25,"count":10,"description":"<b>\u06cc\u06a9 \u06a9\u0645\u067e\u0627\u0646\u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u06af\u06cc \u0645\u0648\u0641\u0642<\/b>\r\n\r\n<span style=\"font-weight: 400;\">Boehringer-Ingelheim \u06cc\u06a9 \u06af\u0631\u0648\u0647 \u062c\u0647\u0627\u0646\u06cc \u0627\u0632 \u0634\u0631\u06a9\u062a\u0647\u0627\u0633\u062a \u06a9\u0647 \u0641\u0631\u0647\u0646\u06af\u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f \u0648 \u062c\u0648\u0627\u0645\u0639 \u06af\u0648\u0646\u0627\u06af\u0648\u0646 \u0631\u0627 \u062f\u0631 \u0628\u0631\u0645\u06cc \u06af\u06cc\u0631\u062f.\u00a0<\/span>\r\n\r\n<span style=\"font-weight: 400;\">\u0647\u062f\u0641 \u0627\u06cc\u0646 \u06a9\u0645\u067e\u0627\u0646\u06cc \u062f\u0627\u0631\u0648\u06cc\u06cc \u067e\u0698\u0648\u0647\u0634 \u0645\u062d\u0648\u0631\u060c \u0628\u0647\u0628\u0648\u062f \u0633\u0644\u0627\u0645\u062a \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0632\u0646\u062f\u06af\u06cc \u0627\u0646\u0633\u0627\u0646\u0647\u0627 \u0648 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u0627\u0633\u062a \u0648 \u062a\u0645\u0631\u06a9\u0632 \u0622\u0646 \u0631\u0648\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc\u06cc \u0645\u06cc\u0628\u0627\u0634\u062f \u06a9\u0647 \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0631\u0627\u06cc \u0622\u0646\u0647\u0627 \u062f\u0631\u0645\u0627\u0646 \u0631\u0636\u0627\u06cc\u062a \u0628\u062e\u0634\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0631\u0648\u06cc \u062a\u0648\u0633\u0639\u0647 \u062f\u0631\u0645\u0627\u0646\u0647\u0627\u06cc \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u0647 \u0627\u06cc \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0639\u0645\u0631 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u062f \u0648 \u062f\u0631 \u062e\u0635\u0648\u0635 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a\u060c \u0628\u0631 \u0631\u0648\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc\u060c \u0645\u062a\u0645\u0631\u06a9\u0632 \u0627\u0633\u062a.<\/span>\r\n\r\n<b>\u0686\u0634\u0645 \u0627\u0646\u062f\u0627\u0632\u0647\u0627 \u0648 \u0627\u0631\u0632\u0634\u0647\u0627<\/b>\r\n\r\n<span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0628\u06cc\u0634 \u0627\u0632 130 \u0633\u0627\u0644 \u0627\u0632 \u0632\u0645\u0627\u0646 \u062a\u0627\u0633\u06cc\u0633 \u062a\u0648\u0633\u0637 Albert Boehringer\u060c \u0647\u0645\u0648\u0627\u0631\u0647 \u062a\u0645\u0631\u06a9\u0632 \u0645\u0627 \u0631\u0648\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0628\u0648\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u0645\u062d\u062f\u0648\u062f \u0634\u062f\u0646 \u0628\u0647 \u0633\u0648\u062f\u0647\u0627\u06cc \u06a9\u0648\u062a\u0627\u0647 \u0645\u062f\u062a.<\/span>\r\n\r\n<b>\u062a\u0627\u0631\u06cc\u062e\u0686\u0647<\/b>\r\n\r\n<span style=\"font-weight: 400;\">\u06a9\u0645\u067e\u0627\u0646\u06cc \u062f\u0627\u0631\u0648\u06cc\u06cc Boehringer-Ingelheim \u062f\u0631 \u0633\u0627\u0644 1885 \u062a\u0648\u0633\u0637 Albert Boehringer \u062f\u0631 Ingelheim am Rhein \u062a\u0627\u0633\u06cc\u0633 \u0634\u062f \u00a0 \u00a0 (1939 <\/span><span style=\"font-weight: 400;\">\u2013<\/span><span style=\"font-weight: 400;\"> 1861). \u0627\u0632 \u0622\u0646 \u0632\u0645\u0627\u0646 \u06a9\u0647 \u0634\u0631\u06a9\u062a \u06a9\u0627\u0631 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0633\u0627\u0644 1885 \u0641\u0642\u0637 \u0628\u0627 28 \u06a9\u0627\u0631\u0645\u0646\u062f \u062f\u0631 Nieder-Ingelheim \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f \u062a\u0627 \u0627\u06a9\u0646\u0648\u0646\u060c \u0628\u0647 \u06cc\u06a9 \u0634\u0631\u06a9\u062a \u062c\u0647\u0627\u0646\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a.\u00a0<\/span>\r\n\r\n<span style=\"font-weight: 400;\">\u0628\u0639\u0646\u0648\u0627\u0646 \u0628\u062e\u0634\u06cc \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u067e\u0698\u0648\u0647\u0634\u06cc \u0648 \u062a\u0648\u0633\u0639\u0647 \u0627\u06cc \u0628\u0631\u0627\u06cc \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u060c \u06a9\u0645\u067e\u0627\u0646\u06cc \u0627\u0628\u062a\u062f\u0627 \u0631\u0648\u06cc \u062d\u0648\u0632\u0647 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u0642\u0644\u0628\u06cc <\/span><span style=\"font-weight: 400;\">\u2013<\/span><span style=\"font-weight: 400;\"> \u0639\u0631\u0648\u0642\u06cc\u060c \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u062a\u0646\u0641\u0633\u06cc\u060c \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u0639\u0635\u0628\u06cc \u0645\u0631\u06a9\u0632\u06cc\u060c \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u0645\u062a\u0627\u0628\u0648\u0644\u06cc\u06a9\u060c \u0628\u06cc\u0645\u0627\u0631\u06cc\u0647\u0627\u06cc \u0648\u06cc\u0631\u0648\u0633\u06cc \u0648 \u0627\u0646\u06a9\u0648\u0644\u0648\u0698\u06cc \u062a\u0645\u0631\u06a9\u0632 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a.<\/span>","link":"https:\/\/fa.hafshejan-co.com\/veterinary\/brands\/boehringer-ingelheim\/","name":"Boehringer-Ingelheim","slug":"boehringer-ingelheim","taxonomy":"brands","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/fa.hafshejan-co.com\/veterinary\/wp-json\/wp\/v2\/brands\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fa.hafshejan-co.com\/veterinary\/wp-json\/wp\/v2\/brands"}],"about":[{"href":"https:\/\/fa.hafshejan-co.com\/veterinary\/wp-json\/wp\/v2\/taxonomies\/brands"}],"wp:post_type":[{"href":"https:\/\/fa.hafshejan-co.com\/veterinary\/wp-json\/wp\/v2\/product?brands=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}